{"id":169822,"date":"2024-01-03T16:06:57","date_gmt":"2024-01-03T15:06:57","guid":{"rendered":"https:\/\/arlettipartners.com\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/"},"modified":"2025-10-03T16:59:17","modified_gmt":"2025-10-03T14:59:17","slug":"aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024","status":"publish","type":"news","link":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/","title":{"rendered":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-nuovo-aumento-del-salario-minimo-francese-in-vigore-dal-1-gennaio-2024\">Nuovo aumento del salario minimo francese in vigore dal 1\u00b0 gennaio 2024 <\/h2>\n\n\n\n<p>In virt\u00f9 dell\u2019andamento dell\u2019inflazione in Francia, all\u2019inizio di ogni anno, il reddito minimo viene adeguato di conseguenza.<\/p>\n\n\n\n<p>In seguito al <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000048604676\" target=\"_blank\" rel=\"noopener\">Decreto del 20 dicembre 2023<\/a>, a partire dal 1\u00b0 gennaio 2024 lo <strong>SMIC \u00e8 aumentato a \u20ac11,65<\/strong>, subendo quindi un aumento dell\u20191,13% rispetto allo <a href=\"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-maggio-2023\/?lang=it\">scorso aumento del maggio 2023<\/a>, in cui il salario minimo orario era stato fissato ad \u20ac11,52.<\/p>\n\n\n\n<p>L\u2019andamento dell\u2019anno appena concluso ha portato ad un aumento dello <strong>stipendio mensile minimo netto<\/strong> da \u20ac1.353,07 (nel mese di gennaio 2023) a <strong>\u20ac1.383,08<\/strong> (per il mese di dicembre 2023).<\/p>\n\n\n\n<p>Con l\u2019ultimo aggiornamento in vigore dal 1\u00b0 gennaio 2024, quindi, la retribuzione lorda di un lavoratore impiegato per 35 ore di lavoro alla settimana ammonta ad un mensile di \u20ac1.766,92 (11,65\u20ac\/ora), per un <strong>netto di <strong>\u20ac1.398,70<\/strong> al mese<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partire dal nuovo anno, entra in vigore il nuovo aumento del salario minimo francese.<\/p>\n","protected":false},"author":1,"featured_media":169814,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[1463],"tags":[],"country":[1563],"container":[],"service":[5576],"tag-di-competenza":[5605],"class_list":["post-169822","news","type-news","status-publish","has-post-thumbnail","hentry","category-remuneration","country-francia","service-posting-of-workers-to-eu","tag-di-competenza-team-posting-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024 - Arletti Partners<\/title>\n<meta name=\"description\" content=\"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all&#039;ultimo incremento di maggio 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024\" \/>\n<meta property=\"og:description\" content=\"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all&#039;ultimo incremento di maggio 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T14:59:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/\"},\"author\":{\"name\":\"Arl21_wpadmin\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/person\\\/675f2c4fe9f8fe4ba74734daf4489581\"},\"headline\":\"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024\",\"datePublished\":\"2024-01-03T15:06:57+00:00\",\"dateModified\":\"2025-10-03T14:59:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/\"},\"wordCount\":135,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Progetto-senza-titolo-28.png\",\"articleSection\":[\"Remuneration\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/\",\"name\":\"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024 - Arletti Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Progetto-senza-titolo-28.png\",\"datePublished\":\"2024-01-03T15:06:57+00:00\",\"dateModified\":\"2025-10-03T14:59:17+00:00\",\"description\":\"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all'ultimo incremento di maggio 2023.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Progetto-senza-titolo-28.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Progetto-senza-titolo-28.png\",\"width\":1300,\"height\":700,\"caption\":\"French SMIC increases as from January 1 2024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?post_type=news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Labour Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/labour-law\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Posting of Workers for Provisions of Services\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/labour-law\\\/posting-of-workers-for-provisions-of-services\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Remuneration\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/diritto-del-lavoro\\\/distacco-dei-lavoratori\\\/livelli-salariali\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/person\\\/675f2c4fe9f8fe4ba74734daf4489581\",\"name\":\"Arl21_wpadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"caption\":\"Arl21_wpadmin\"},\"sameAs\":[\"https:\\\/\\\/arlettipartners.com\"],\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/author\\\/arl21_wpadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024 - Arletti Partners","description":"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all'ultimo incremento di maggio 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024","og_description":"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all'ultimo incremento di maggio 2023.","og_url":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_modified_time":"2025-10-03T14:59:17+00:00","og_image":[{"width":1300,"height":700,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/"},"author":{"name":"Arl21_wpadmin","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/person\/675f2c4fe9f8fe4ba74734daf4489581"},"headline":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024","datePublished":"2024-01-03T15:06:57+00:00","dateModified":"2025-10-03T14:59:17+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/"},"wordCount":135,"publisher":{"@id":"https:\/\/arlettipartners.com\/it\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png","articleSection":["Remuneration"],"inLanguage":"it-IT","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/arlettipartners.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/","url":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/","name":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024 - Arletti Partners","isPartOf":{"@id":"https:\/\/arlettipartners.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png","datePublished":"2024-01-03T15:06:57+00:00","dateModified":"2025-10-03T14:59:17+00:00","description":"A partire dal 1\u00b0 gennaio 2024, il salario minimo in Francia aumenta del 1,13% rispetto all'ultimo incremento di maggio 2023.","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/01\/Progetto-senza-titolo-28.png","width":1300,"height":700,"caption":"French SMIC increases as from January 1 2024"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/it\/aumento-del-salario-minimo-francese-a-partire-dal-1-gennaio-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/arlettipartners.com\/it\/?post_type=news"},{"@type":"ListItem","position":3,"name":"Labour Law","item":"https:\/\/arlettipartners.com\/it\/category\/labour-law\/"},{"@type":"ListItem","position":4,"name":"Posting of Workers for Provisions of Services","item":"https:\/\/arlettipartners.com\/it\/category\/labour-law\/posting-of-workers-for-provisions-of-services\/"},{"@type":"ListItem","position":5,"name":"Remuneration","item":"https:\/\/arlettipartners.com\/it\/category\/diritto-del-lavoro\/distacco-dei-lavoratori\/livelli-salariali\/"},{"@type":"ListItem","position":6,"name":"Aumento del salario minimo francese a partire dal 1\u00b0 gennaio 2024"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/it\/#website","url":"https:\/\/arlettipartners.com\/it\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/it\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/person\/675f2c4fe9f8fe4ba74734daf4489581","name":"Arl21_wpadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","caption":"Arl21_wpadmin"},"sameAs":["https:\/\/arlettipartners.com"],"url":"https:\/\/arlettipartners.com\/it\/author\/arl21_wpadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news\/169822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news\/169822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/media\/169814"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/media?parent=169822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories?post=169822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tags?post=169822"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/country?post=169822"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container?post=169822"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/service?post=169822"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tag-di-competenza?post=169822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}