{"id":114060,"date":"2021-03-29T10:10:21","date_gmt":"2021-03-29T08:10:21","guid":{"rendered":"https:\/\/arlettipartners.com\/?p=114060"},"modified":"2025-12-04T09:36:45","modified_gmt":"2025-12-04T08:36:45","slug":"superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv","status":"publish","type":"news","link":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/","title":{"rendered":"Superbonus: Organizzazioni non lucrative di utilit\u00e0 sociale (ONLUS), organizzazioni di volontariato (OdV)."},"content":{"rendered":"<p style=\"text-align: left;\">Un&#8217;associazione di promozione sociale vuole accedere alle detrazioni maggiorate del 110%, per lavori che oggettivamente rientrano nella casistica soggetta al Superbonus su immobili non abitativi a disposizione della stessa associazione, utilizzati a fini istituzionali. L&#8217;Agenzia delle Entrate chiarisce l&#8217;accesso al Superbonus per ONLUS e OdV.<\/p>\n<h2 style=\"text-align: left;\">Superbonus per ONLUS e OdV: il caso<\/h2>\n<p style=\"text-align: left;\">Con la risposta n. 206 del 25 marzo 2021, l&#8217;Agenzia delle Entrate ha chiarito i dubbi di un&#8217;associazione di promozione sociale, intenzionata a effettuare lavori antisismici e di efficientamento energetico su immobili non abitativi (rientranti nelle categorie catastali D\/6 e D\/8) utilizzati a fini istituzionali dall&#8217;associazione stessa.<\/p>\n<h2 style=\"text-align: left;\">La precisazione dell&#8217;Agenzia delle Entrate<\/h2>\n<p style=\"text-align: left;\">L&#8217;Agenzia delle entrate ricorda come, con la circolare n. 30\/2020, \u00e8 gi\u00e0 stato precisato che il Superbonus si applica anche agli interventi effettuati dalle organizzazioni non lucrative di utilit\u00e0 sociale (Onlus), dalle organizzazioni di volontariato (Odv) e dalle associazioni di promozione sociale (Aps) iscritte nei registri nazionali, regionali e delle provincie autonome di Trento e Bolzano.<\/p>\n<p style=\"text-align: left;\">Per queste tre categorie di beneficiari, sottolinea l&#8217;Agenzia, la normativa non prevede alcuna limitazione in merito alla tipologia di immobili, consentendo quindi di accedere al Superbonus per tutti gli interventi agevolabili, indipendentemente dalla categoria catastale e dalla destinazione dell&#8217;immobile.<\/p>\n<h2 style=\"text-align: left;\">Conclusione: la conferma dell&#8217;Agenzia<\/h2>\n<p style=\"text-align: left;\">In conclusione, l&#8217;Agenzia conferma che all&#8217;associazione di promozione sociale non \u00e8 precluso l&#8217;accesso al Superbonus per gli interventi sugli immobili di categoria D\/6 e D\/8, naturalmente in presenza dei requisiti previsti dalla normativa e ferma restando la necessit\u00e0 che gli interventi ammessi al 110% siano effettuati sull&#8217;intero edificio o sulle singole unit\u00e0 immobiliari.<\/p>\n<p style=\"text-align: left;\">Risposta n. 206 del 26\/03\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell&#8217;Agenzia delle Entrate alle associazioni di promozione sociale.<\/p>\n","protected":false},"author":11,"featured_media":123871,"template":"","meta":{"_acf_changed":false,"_angie_page":false,"footnotes":""},"categories":[1678,1450],"tags":[],"country":[1503],"container":[],"service":[],"tag-di-competenza":[5604],"class_list":["post-114060","news","type-news","status-publish","has-post-thumbnail","hentry","category-building-bonuses","category-income-tax-law","country-italia","tag-di-competenza-team-fiscale-italia-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Superbonus per ONLUS: risponde l&#039;Agenzia delle Entrate - Arletti Partners<\/title>\n<meta name=\"description\" content=\"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell&#039;Agenzia delle Entrate alle associazioni di promozione sociale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superbonus: Organizzazioni non lucrative di utilit\u00e0 sociale (ONLUS), organizzazioni di volontariato (OdV).\" \/>\n<meta property=\"og:description\" content=\"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell&#039;Agenzia delle Entrate alle associazioni di promozione sociale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-04T08:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2021\/10\/Progetto-senza-titolo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/\",\"name\":\"Superbonus per ONLUS: risponde l'Agenzia delle Entrate - Arletti Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Progetto-senza-titolo.png\",\"datePublished\":\"2021-03-29T08:10:21+00:00\",\"dateModified\":\"2025-12-04T08:36:45+00:00\",\"description\":\"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell'Agenzia delle Entrate alle associazioni di promozione sociale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Progetto-senza-titolo.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Progetto-senza-titolo.png\",\"width\":1600,\"height\":900,\"caption\":\"superbonus 110 diventa superbonus 90 a partire da gennaio 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?post_type=news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tax Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/legge-fiscale\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Income Tax Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/imposte-sul-reddito\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Tax Credits\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/tax-credits\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Building Bonuses\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/bonus-edilizi\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"Superbonus: Organizzazioni non lucrative di utilit\u00e0 sociale (ONLUS), organizzazioni di volontariato (OdV).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Superbonus per ONLUS: risponde l'Agenzia delle Entrate - Arletti Partners","description":"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell'Agenzia delle Entrate alle associazioni di promozione sociale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/","og_locale":"it_IT","og_type":"article","og_title":"Superbonus: Organizzazioni non lucrative di utilit\u00e0 sociale (ONLUS), organizzazioni di volontariato (OdV).","og_description":"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell'Agenzia delle Entrate alle associazioni di promozione sociale.","og_url":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_modified_time":"2025-12-04T08:36:45+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2021\/10\/Progetto-senza-titolo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/","url":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/","name":"Superbonus per ONLUS: risponde l'Agenzia delle Entrate - Arletti Partners","isPartOf":{"@id":"https:\/\/arlettipartners.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2021\/10\/Progetto-senza-titolo.png","datePublished":"2021-03-29T08:10:21+00:00","dateModified":"2025-12-04T08:36:45+00:00","description":"Detrazioni maggiorate del Superbonus per ONLUS e OdV: la risposta dell'Agenzia delle Entrate alle associazioni di promozione sociale.","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2021\/10\/Progetto-senza-titolo.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2021\/10\/Progetto-senza-titolo.png","width":1600,"height":900,"caption":"superbonus 110 diventa superbonus 90 a partire da gennaio 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/it\/superbonus-organizzazioni-non-lucrative-di-utilita-sociale-onlus-organizzazioni-di-volontariato-odv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/arlettipartners.com\/it\/?post_type=news"},{"@type":"ListItem","position":3,"name":"Tax Law","item":"https:\/\/arlettipartners.com\/it\/category\/legge-fiscale\/"},{"@type":"ListItem","position":4,"name":"Income Tax Law","item":"https:\/\/arlettipartners.com\/it\/category\/imposte-sul-reddito\/"},{"@type":"ListItem","position":5,"name":"Tax Credits","item":"https:\/\/arlettipartners.com\/it\/category\/tax-credits\/"},{"@type":"ListItem","position":6,"name":"Building Bonuses","item":"https:\/\/arlettipartners.com\/it\/category\/bonus-edilizi\/"},{"@type":"ListItem","position":7,"name":"Superbonus: Organizzazioni non lucrative di utilit\u00e0 sociale (ONLUS), organizzazioni di volontariato (OdV)."}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/it\/#website","url":"https:\/\/arlettipartners.com\/it\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/it\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news\/114060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":1,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news\/114060\/revisions"}],"predecessor-version":[{"id":223386,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news\/114060\/revisions\/223386"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/media?parent=114060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories?post=114060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tags?post=114060"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/country?post=114060"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container?post=114060"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/service?post=114060"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tag-di-competenza?post=114060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}