{"id":235228,"date":"2026-05-07T15:32:40","date_gmt":"2026-05-07T13:32:40","guid":{"rendered":"https:\/\/arlettipartners.com\/container\/distacco-dei-lavoratori-nell-ue-see-e-svizzera\/"},"modified":"2026-05-26T11:54:57","modified_gmt":"2026-05-26T09:54:57","slug":"distacco-dei-lavoratori-nell-ue-see-e-svizzera","status":"publish","type":"container","link":"https:\/\/arlettipartners.com\/it\/container\/distacco-dei-lavoratori-nell-ue-see-e-svizzera\/","title":{"rendered":"Conformit\u00e0 sul Distacco dei lavoratori nell\u2019UE, SEE e Svizzera"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":228594,"parent":0,"template":"","meta":{"_acf_changed":false,"_angie_page":false,"footnotes":""},"categories":[1717,1438,1417,1422,1459],"tags":[7763],"country":[2252,1533,2265],"container":[7752],"individualscorporates":[7819],"raggruppamento":[],"service":[7602],"tag-di-competenza":[5627],"class_list":["post-235228","container","type-container","status-publish","has-post-thumbnail","hentry","category-posting-of-workers-for-provisions-of-services","category-work-visa","category-health-safety-at-work-for-employees","category-immigration-law","category-labour-law","tag-hub","country-spazio-economico-europeo","country-unione-europea","country-svizzera","container-posting-of-workers","individualscorporates-corporates","service-posting-of-workers-eng","tag-di-competenza-team-giuridico-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arletti Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":null,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arletti Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"it_IT","og_type":"article","og_site_name":"Arletti Partners","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":null,"url":"","name":"","isPartOf":{"@id":"https:\/\/arlettipartners.com\/it\/#website"},"inLanguage":"it-IT"},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/it\/#website","url":"https:\/\/arlettipartners.com\/it\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/it\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container\/235228"}],"collection":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container"}],"about":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/types\/container"}],"version-history":[{"count":1,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container\/235228\/revisions"}],"predecessor-version":[{"id":235842,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container\/235228\/revisions\/235842"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/media?parent=235228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories?post=235228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tags?post=235228"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/country?post=235228"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container?post=235228"},{"taxonomy":"individualscorporates","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/individualscorporates?post=235228"},{"taxonomy":"raggruppamento","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/raggruppamento?post=235228"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/service?post=235228"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/tag-di-competenza?post=235228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}