{"id":5172,"count":5,"description":"","link":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/","name":"Citizenship by Descent","slug":"citizenship-by-descent","taxonomy":"category","parent":1426,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Citizenship by Descent Archives - Arletti Partners<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citizenship by Descent Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/citizenship\\\/citizenship-by-descent\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/citizenship\\\/citizenship-by-descent\\\/\",\"name\":\"Citizenship by Descent Archives - Arletti Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/citizenship\\\/citizenship-by-descent\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/citizenship\\\/citizenship-by-descent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immigration Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Citizenship\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/category\\\/immigration-law\\\/citizenship\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Citizenship by Descent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Citizenship by Descent Archives - Arletti Partners","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/","og_locale":"it_IT","og_type":"article","og_title":"Citizenship by Descent Archives","og_url":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/","og_site_name":"Arletti Partners","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/","url":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/","name":"Citizenship by Descent Archives - Arletti Partners","isPartOf":{"@id":"https:\/\/arlettipartners.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/citizenship-by-descent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/it\/"},{"@type":"ListItem","position":2,"name":"Immigration Law","item":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/"},{"@type":"ListItem","position":3,"name":"Citizenship","item":"https:\/\/arlettipartners.com\/it\/category\/immigration-law\/citizenship\/"},{"@type":"ListItem","position":4,"name":"Citizenship by Descent"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/it\/#website","url":"https:\/\/arlettipartners.com\/it\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/it\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories\/5172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/categories\/1426"}],"wp:post_type":[{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/posts?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/announcements-awwa?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/calendly-post?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/collaboration?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/container?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/credit?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/form-post?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/news?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/regulatory-framework?categories=5172"},{"href":"https:\/\/arlettipartners.com\/it\/wp-json\/wp\/v2\/services?categories=5172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}