{"id":179755,"date":"2024-03-21T15:01:06","date_gmt":"2024-03-21T14:01:06","guid":{"rendered":"https:\/\/arlettipartners.com\/detachement-de-travailleurs-en-hongrie\/"},"modified":"2024-08-20T16:18:59","modified_gmt":"2024-08-20T14:18:59","slug":"detachement-de-travailleurs-en-hongrie","status":"publish","type":"post","link":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/","title":{"rendered":"D\u00e9tachement de travailleurs en Hongrie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Les <a href=\"https:\/\/arlettipartners.com\/directive-96-71-ce-conditions-de-travail-equitables-au-dela-des-frontieres-nationales\/?lang=fr\">directives 96\/71\/CE<\/a>, <a href=\"https:\/\/arlettipartners.com\/detachements-transnationaux-la-directive-2014-67-ue\/?lang=fr\">2014\/67\/UE<\/a> et 2018\/957\/UE, qui r\u00e9gissent le <a href=\"https:\/\/arlettipartners.com\/detachement-de-travailleurs-dans-lue\/?lang=fr\">d\u00e9tachement des travailleurs dans l&#8217;UE<\/a>, ont \u00e9t\u00e9 transpos\u00e9es en Hongrie dans la l\u00e9gislation suivante :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Loi I de 2012 sur le Code du Travail ; <\/li>\n\n\n\n<li>Loi CXXXV de 2020 ; <\/li>\n\n\n\n<li>D\u00e9cret gouvernemental n\u00b0 115\/2021 (III. 10.) et <\/li>\n\n\n\n<li>D\u00e9cret gouvernemental n\u00b0 703\/2021 (XII. 15.). <\/li>\n<\/ul>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Pour plus d&#8217;informations sur la l\u00e9gislation de l&#8217;UE concernant le d\u00e9tachement des travailleurs, consultez notre guide complet sur les <a href=\"https:\/\/arlettipartners.com\/reglementation-travailleurs-detaches-directives-ue-detachement\/?lang=fr\">directives de l&#8217;UE relatives au d\u00e9tachement.<\/a><\/p>\n<\/blockquote>\n\n<h2 class=\"wp-block-heading\" id=\"h-preliminary-requirements-for-posting-workers-to-hungary\">Obligations pr\u00e9liminaires pour le d\u00e9tachement de travailleurs en Hongrie<\/h2>\n\n<p class=\"wp-block-paragraph\">Les entreprises qui d\u00e9tachent leurs employ\u00e9s en Hongrie sont tenues de soumettre une <a href=\"https:\/\/arlettipartners.com\/declaration-de-detachement\/?lang=fr\">d\u00e9claration de d\u00e9tachement<\/a> aux autorit\u00e9s d&#8217;inspection du pays via le site web institutionnel mis \u00e0 disposition par les autorit\u00e9s. La d\u00e9claration de d\u00e9tachement doit \u00eatre transmise au plus tard avant le d\u00e9but des activit\u00e9s professionnelles en Hongrie.<\/p>\n\n<p class=\"wp-block-paragraph\">La d\u00e9claration de d\u00e9tachement doit inclure les informations suivantes : <\/p>\n\n<ol class=\"wp-block-list\">\n<li>Donn\u00e9es relatives au <strong>prestataire de services<\/strong> (d\u00e9nomination sociale, adresse, etc.) ;<\/li>\n\n\n\n<li>Donn\u00e9es relatives \u00e0 la <strong>nature de l&#8217;activit\u00e9<\/strong> exerc\u00e9e en territoire hongrois ;<\/li>\n\n\n\n<li>Donn\u00e9es relatives aux <strong>travailleurs<\/strong> d\u00e9tach\u00e9s ;<\/li>\n\n\n\n<li>Donn\u00e9es relatives \u00e0 la prestation de services (<strong>dur\u00e9e<\/strong> du d\u00e9tachement, <strong>lieu<\/strong> de travail, etc.).<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">L&#8217;entreprise qui d\u00e9tache ses travailleurs doit \u00e9galement <strong>nommer une personne de contact<\/strong> agissant en tant qu&#8217;interm\u00e9diaire ou lien avec les autorit\u00e9s. Cette personne de contact doit \u00eatre disponible sur le territoire hongrois. Les informations de cette personne doivent \u00eatre indiqu\u00e9es dans la section correspondante de la d\u00e9claration de d\u00e9tachement.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-working-and-salary-conditions-applicable-during-posting-in-hungary\">Conditions de travail et salariales applicables lors de la mission en Hongrie<\/h2>\n\n<p class=\"wp-block-paragraph\">L&#8217;article 295 de la loi I de 2012 sur le Code du Travail stipule que si un salari\u00e9 est temporairement d\u00e9tach\u00e9 par un employeur \u00e9tranger en Hongrie, ce salari\u00e9 est soumis \u00e0 certaines conditions minimales garanties par le <strong>droit du travail hongrois<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Les dispositions du Code du Travail concernant les d\u00e9tachements en Hongrie couvrent les <strong>horaires de travail<\/strong>, les <strong>pauses<\/strong> et le <strong>salaire minimum<\/strong>.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les normes minimales concernant le temps de travail sont \u00e9tablies au niveau europ\u00e9en. Pour plus d&#8217;informations, consultez notre guide sur la <a href=\"https:\/\/arlettipartners.com\/directive-2003-88-ce-temps-de-travail-sur-le-marche-europeen\/?lang=fr\">directive europ\u00e9enne relative au temps de travail.<\/a><\/p>\n<\/blockquote>\n\n<p class=\"wp-block-paragraph\">En Hongrie, le <strong>salaire minimum<\/strong> \u00e0 verser aux employ\u00e9s occupant des postes n\u00e9cessitant un dipl\u00f4me d&#8217;\u00e9tudes secondaires ou une formation professionnelle avanc\u00e9e ou sup\u00e9rieure est fix\u00e9 \u00e0 <strong>855,00 \u20ac\/mois.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">En tout \u00e9tat de cause, <strong>ces dispositions ne s&#8217;appliquent que si elles sont plus favorables<\/strong> aux travailleurs \u00e9trangers.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Pour plus d&#8217;informations sur la l\u00e9gislation du travail au sein de l&#8217;UE, consultez notre guide sur le <a href=\"https:\/\/arlettipartners.com\/droit-du-travail-de-lunion-europeenne-guide-complet\/?lang=fr\">droit du travail de l&#8217;Union europ\u00e9enne.<\/a><\/p>\n<\/blockquote>\n\n<h2 class=\"wp-block-heading\" id=\"h-social-security-in-hungary\">S\u00e9curit\u00e9 sociale en Hongrie<\/h2>\n\n<p class=\"wp-block-paragraph\">Les travailleurs d\u00e9tach\u00e9s d&#8217;un pays de l&#8217;UE\/EEE ont le droit de maintenir les contributions sociales vers\u00e9es dans leur pays d&#8217;origine. \u00c0 cet \u00e9gard, l&#8217;employeur doit demander le <a href=\"https:\/\/arlettipartners.com\/formulaire-a1-travailleurs-detaches\/?lang=fr\">formulaire A1<\/a> \u00e0 l&#8217;organisme de s\u00e9curit\u00e9 sociale comp\u00e9tent.<\/p>\n\n<p class=\"wp-block-paragraph\">Le certificat A1 prouve que le <strong>travailleur continue de cotiser \u00e0 la s\u00e9curit\u00e9 sociale dans son pays d&#8217;origine<\/strong>. Ce document doit \u00eatre disponible pendant et apr\u00e8s le d\u00e9tachement et sur demande des autorit\u00e9s.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-long-term-assignments-in-hungary-nbsp\">Affectations de longue dur\u00e9e en Hongrie<\/h2>\n\n<p class=\"wp-block-paragraph\">Si la <strong>dur\u00e9e effective du d\u00e9tachement en Hongrie d\u00e9passe 12 mois<\/strong>, ind\u00e9pendamment de la l\u00e9gislation applicable \u00e0 la relation de travail, les entreprises \u00e9tablies dans un \u00c9tat membre doivent garantir aux travailleurs d\u00e9tach\u00e9s toutes les conditions de travail et d&#8217;emploi applicables en Hongrie, notamment :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Dispositions l\u00e9gislatives, r\u00e9glementaires ou administratives, et\/ou <\/li>\n\n\n\n<li>Conventions collectives ou arbitrages d\u00e9clar\u00e9s d&#8217;application g\u00e9n\u00e9rale ou qui, alternativement, s&#8217;appliquent conform\u00e9ment \u00e0 l&#8217;article 3, paragraphe 8, de la directive 96\/71\/CE. <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Ces conditions s&#8217;ajoutent aux conditions de travail et d&#8217;emploi pr\u00e9vues \u00e0 l&#8217;article 3, paragraphe 1, de la directive 96\/71\/CE. <\/p>\n\n<p class=\"wp-block-paragraph\">En cas d&#8217;affectation sup\u00e9rieure \u00e0 12 mois, le prestataire de services devra pr\u00e9senter une <strong>notification motiv\u00e9e<\/strong> aux autorit\u00e9s comp\u00e9tentes du pays d&#8217;accueil. Apr\u00e8s la p\u00e9riode de 12\/18 mois, toutes les conditions suppl\u00e9mentaires en mati\u00e8re d&#8217;emploi s&#8217;appliquent aux travailleurs d\u00e9tach\u00e9s.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-storage-of-documents-concerning-the-posting-in-hungary\">Conservation des documents pendant la mission en Hongrie<\/h2>\n\n<p class=\"wp-block-paragraph\">La r\u00e9glementation relative \u00e0 la conservation et \u00e0 la mise \u00e0 disposition des documents n\u00e9cessaires au d\u00e9tachement des travailleurs est contenue dans la sous-section (3) de l&#8217;article 297 de la loi I de 2012 sur le Code du Travail. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>L&#8217;entreprise d\u00e9tachante<\/strong> est tenue de <strong>conserver les documents suivants<\/strong> :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>&#8211; <strong>Contrats<\/strong> de travail (ou autres documents \u00e9quivalents) ;<\/li>\n\n\n\n<li>&#8211; <strong>Feuilles de pr\u00e9sence<\/strong> et<\/li>\n\n\n\n<li>&#8211; <strong>Preuves de paiement<\/strong> des salaires.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Ces documents doivent \u00eatre <strong>disponibles pendant toute la dur\u00e9e du d\u00e9tachement<\/strong> sous forme papier ou \u00e9lectronique sur le lieu de travail, <strong>et pendant une p\u00e9riode de trois ans apr\u00e8s la fin<\/strong> du d\u00e9tachement au si\u00e8ge social de l&#8217;employeur, \u00e0 des fins de v\u00e9rification.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-penalties-for-non-compliance-according-national-legislation\">Sanctions applicables en cas de non-conformit\u00e9 \u00e0 la l\u00e9gislation nationale<\/h2>\n\n<p class=\"wp-block-paragraph\">Conform\u00e9ment \u00e0 l&#8217;article 19 du d\u00e9cret gouvernemental n\u00b0 115\/2021 (III.10.), l&#8217;autorit\u00e9 du travail impose une amende en cas de violation de la r\u00e9glementation sur l&#8217;archivage de la documentation. Dans ce cas, le montant de l&#8217;amende est \u00e9gal au <strong>salaire minimum multipli\u00e9 par le nombre de travailleurs d\u00e9tach\u00e9s.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">En cas de <strong>non-respect de l&#8217;obligation de notification<\/strong>, l&#8217;article 19 du d\u00e9cret gouvernemental n\u00b0 115\/2021 (III.10.) pr\u00e9voit \u00e9galement une sanction dont le montant est <strong>\u00e9gal au salaire minimum<\/strong> (le nombre de travailleurs d\u00e9tach\u00e9s n&#8217;est pas d\u00e9terminant dans ce cas).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez toutes les exigences et lignes directrices relatives \u00e0 la gestion du d\u00e9tachement de travailleurs en Hongrie : les obligations, les documents n\u00e9cessaires et les sanctions applicables en cas de non-respect de la r\u00e9glementation. <\/p>\n","protected":false},"author":1,"featured_media":173172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_angie_page":false,"page_builder":"","footnotes":""},"categories":[1716],"tags":[],"country":[1572],"container":[6598],"service":[6235],"tag-di-competenza":[5609],"class_list":["post-179755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posting-of-workers-for-provisions-of-services","country-hongrie","container-global-mobility-services","service-posting-of-workers-to-eu","tag-di-competenza-team-posting-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9tachement de travailleurs en Hongrie - Arletti Partners<\/title>\n<meta name=\"description\" content=\"En savoir plus sur les exigences et les lignes directrices relatives au d\u00e9tachement de travailleurs en Hongrie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9tachement de travailleurs en Hongrie\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez toutes les exigences et lignes directrices relatives \u00e0 la gestion du d\u00e9tachement de travailleurs en Hongrie : les obligations, les documents n\u00e9cessaires et les sanctions applicables en cas de non-respect de la r\u00e9glementation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-21T14:01:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T14:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arl21_wpadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arl21_wpadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/\"},\"author\":{\"name\":\"Arl21_wpadmin\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#\\\/schema\\\/person\\\/675f2c4fe9f8fe4ba74734daf4489581\"},\"headline\":\"D\u00e9tachement de travailleurs en Hongrie\",\"datePublished\":\"2024-03-21T14:01:06+00:00\",\"dateModified\":\"2024-08-20T14:18:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/\"},\"wordCount\":944,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/posting-workers-to-hungary.png\",\"articleSection\":[\"Posting of Workers for Provisions of Services\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/\",\"name\":\"D\u00e9tachement de travailleurs en Hongrie - Arletti Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/posting-workers-to-hungary.png\",\"datePublished\":\"2024-03-21T14:01:06+00:00\",\"dateModified\":\"2024-08-20T14:18:59+00:00\",\"description\":\"En savoir plus sur les exigences et les lignes directrices relatives au d\u00e9tachement de travailleurs en Hongrie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/posting-workers-to-hungary.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/posting-workers-to-hungary.png\",\"width\":1300,\"height\":700,\"caption\":\"Posting workers to Hungary\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/detachement-de-travailleurs-en-hongrie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Labour Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/category\\\/labour-law\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Posting of Workers for Provisions of Services\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/category\\\/labour-law\\\/posting-of-workers-for-provisions-of-services\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"D\u00e9tachement de travailleurs en Hongrie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/#\\\/schema\\\/person\\\/675f2c4fe9f8fe4ba74734daf4489581\",\"name\":\"Arl21_wpadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g\",\"caption\":\"Arl21_wpadmin\"},\"sameAs\":[\"https:\\\/\\\/arlettipartners.com\"],\"url\":\"https:\\\/\\\/arlettipartners.com\\\/fr\\\/author\\\/arl21_wpadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9tachement de travailleurs en Hongrie - Arletti Partners","description":"En savoir plus sur les exigences et les lignes directrices relatives au d\u00e9tachement de travailleurs en Hongrie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9tachement de travailleurs en Hongrie","og_description":"D\u00e9couvrez toutes les exigences et lignes directrices relatives \u00e0 la gestion du d\u00e9tachement de travailleurs en Hongrie : les obligations, les documents n\u00e9cessaires et les sanctions applicables en cas de non-respect de la r\u00e9glementation.","og_url":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_published_time":"2024-03-21T14:01:06+00:00","article_modified_time":"2024-08-20T14:18:59+00:00","og_image":[{"width":1300,"height":700,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png","type":"image\/png"}],"author":"Arl21_wpadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Arl21_wpadmin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/"},"author":{"name":"Arl21_wpadmin","@id":"https:\/\/arlettipartners.com\/fr\/#\/schema\/person\/675f2c4fe9f8fe4ba74734daf4489581"},"headline":"D\u00e9tachement de travailleurs en Hongrie","datePublished":"2024-03-21T14:01:06+00:00","dateModified":"2024-08-20T14:18:59+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/"},"wordCount":944,"publisher":{"@id":"https:\/\/arlettipartners.com\/fr\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png","articleSection":["Posting of Workers for Provisions of Services"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/","url":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/","name":"D\u00e9tachement de travailleurs en Hongrie - Arletti Partners","isPartOf":{"@id":"https:\/\/arlettipartners.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png","datePublished":"2024-03-21T14:01:06+00:00","dateModified":"2024-08-20T14:18:59+00:00","description":"En savoir plus sur les exigences et les lignes directrices relatives au d\u00e9tachement de travailleurs en Hongrie","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2024\/03\/posting-workers-to-hungary.png","width":1300,"height":700,"caption":"Posting workers to Hungary"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/fr\/detachement-de-travailleurs-en-hongrie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Labour Law","item":"https:\/\/arlettipartners.com\/fr\/category\/labour-law\/"},{"@type":"ListItem","position":3,"name":"Posting of Workers for Provisions of Services","item":"https:\/\/arlettipartners.com\/fr\/category\/labour-law\/posting-of-workers-for-provisions-of-services\/"},{"@type":"ListItem","position":4,"name":"D\u00e9tachement de travailleurs en Hongrie"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/fr\/#website","url":"https:\/\/arlettipartners.com\/fr\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/fr\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arlettipartners.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/fr\/#\/schema\/person\/675f2c4fe9f8fe4ba74734daf4489581","name":"Arl21_wpadmin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4840d26b3ad1e6d1918e55d982f6d70375ce48193435cbfb611dbbb8e1f95a0?s=96&d=mm&r=g","caption":"Arl21_wpadmin"},"sameAs":["https:\/\/arlettipartners.com"],"url":"https:\/\/arlettipartners.com\/fr\/author\/arl21_wpadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/posts\/179755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/comments?post=179755"}],"version-history":[{"count":0,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/posts\/179755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/media\/173172"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/media?parent=179755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/categories?post=179755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/tags?post=179755"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/country?post=179755"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/container?post=179755"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/service?post=179755"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/fr\/wp-json\/wp\/v2\/tag-di-competenza?post=179755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}