{"id":194530,"date":"2025-03-27T12:13:51","date_gmt":"2025-03-27T11:13:51","guid":{"rendered":"https:\/\/arlettipartners.com\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/"},"modified":"2025-12-12T11:30:54","modified_gmt":"2025-12-12T10:30:54","slug":"permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias","status":"publish","type":"post","link":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/","title":{"rendered":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas"},"content":{"rendered":"&#13;\n<h2 id=\"h-overview-of-key-requirements-for-assignments-in-switzerland\" class=\"wp-block-heading\">Resumen de los principales requisitos para las misiones en Suiza<\/h2>&#13;\n\r\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-2c90304e wp-block-group-is-layout-flex\">&#13;\n<h3 id=\"h-posting-notification\" class=\"wp-block-heading\">Notificaci\u00f3n de Desplazamiento<\/h3>&#13;\n\r\n\r\n&#13;\n<p class=\"wp-block-paragraph\">Las empresas de la UE\/EEE\/Reino Unido deben notificarlo a las autoridades cantonales suizas a trav\u00e9s del <a href=\"https:\/\/meweb.admin.ch\/meldeverfahren\/\" target=\"_blank\" rel=\"noopener\">portal en l\u00ednea<\/a> espec\u00edfico al menos <strong>8 d\u00edas antes del inicio de las actividades<\/strong>.<\/p>&#13;\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">&#13;\n<p class=\"wp-block-paragraph\"><strong>Excepciones:<\/strong> En casos urgentes, como reparaciones o incidencias imprevistas, los trabajos podr\u00e1n comenzar antes del plazo de 8 d\u00edas, siempre que se pueda demostrar la urgencia.<\/p>&#13;\n<\/blockquote>\r\n\r\n\r\n&#13;\n<p class=\"wp-block-paragraph\">Cada empresa puede beneficiarse de <strong>8 d\u00edas de exenci\u00f3n de la obligaci\u00f3n de notificaci\u00f3n por a\u00f1o civil<\/strong>. Sin embargo, esta exenci\u00f3n no se aplica a las actividades de los siguientes sectores:<\/p>&#13;\n\r\n\r\n\r\n<ul class=\"wp-block-list\">&#13;\n<li>Construcci\u00f3n<\/li>&#13;\n\r\n\r\n&#13;\n<li>Paisajismo<\/li>&#13;\n\r\n\r\n&#13;\n<li>Hosteler\u00eda y restauraci\u00f3n<\/li>&#13;\n\r\n\r\n&#13;\n<li>Limpieza industrial y dom\u00e9stica<\/li>&#13;\n\r\n\r\n&#13;\n<li>Servicios de vigilancia y seguridad<\/li>&#13;\n\r\n\r\n&#13;\n<li>Comercio ambulante<\/li>&#13;\n<\/ul>\r\n\r\n\r\n&#13;\n<p class=\"wp-block-paragraph\">Cada empresa dispone de <strong>90 d\u00edas por a\u00f1o civil<\/strong> para publicar notificaciones.<\/p>&#13;\n\r\n\r\n&#13;\n<p class=\"wp-block-paragraph\">El procedimiento de notificaci\u00f3n se aplica a los trabajadores con ciudadan\u00eda de la UE y a los no nacionales de la UE que residen legalmente en un pa\u00eds de la UE. No obstante, los trabajadores extracomunitarios deben haber estado registrados en el mercado laboral de un Estado miembro de la UE durante al menos <strong>12 meses antes de entrar en Suiza<\/strong>.<\/p>&#13;\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">&#13;\n<p class=\"wp-block-paragraph\">Para m\u00e1s detalles sobre todas las obligaciones, lea <a href=\"https:\/\/arlettipartners.com\/desplazamiento-de-trabajadores-a-suiza\/?lang=es\">nuestro art\u00edculo sobre el desplazamiento de trabajadores a Suiza<\/a>.<\/p>&#13;\n<\/blockquote>\r\n<\/div>\r\n&#13;\n<h3 id=\"h-compliance-with-working-and-wage-conditions\" class=\"wp-block-heading\">Cumplimiento de las condiciones laborales y salariales<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Durante el desplazamiento, el empleador debe garantizar que los trabajadores desplazados reciban al menos las condiciones laborales y salariales m\u00ednimas prescritas por la legislaci\u00f3n suiza.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">En particular, el empleador debe respetar el salario m\u00ednimo, incluidos los posibles complementos, as\u00ed como los periodos de trabajo y descanso.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">En Suiza no existe un salario m\u00ednimo nacional. Por lo tanto, las empresas que desplazan trabajadores a Suiza deben cumplir los niveles salariales m\u00ednimos establecidos por los convenios colectivos aplicables a cada cant\u00f3n.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">La jornada laboral no debe superar la duraci\u00f3n m\u00e1xima diaria de <strong>10 horas (incluidas las horas extraordinarias)<\/strong> ni el l\u00edmite semanal de <strong>45 horas<\/strong>. Adem\u00e1s, los trabajadores deben hacer una pausa de al menos <strong>1 hora<\/strong> durante la jornada laboral si esta supera las 9 horas.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Por \u00faltimo, siempre es necesario llevar una hoja de horas in situ, que debe ser firmada diariamente tanto por el empleado como por el cliente suizo.<\/p>&#13;\n&#13;\n<h3 id=\"h-a1-certificate-application\" class=\"wp-block-heading\">Solicitud del Modelo A1<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Para el periodo de trabajo realizado en Suiza, la empresa que desplaza debe solicitar la expedici\u00f3n del <a href=\"https:\/\/arlettipartners.com\/modelo-a1\/?lang=es\">Modelo A1<\/a> a la instituci\u00f3n de seguridad social competente del pa\u00eds de origen.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">El Modelo A1 confirma que el trabajador desplazado sigue estando asegurado a efectos de seguridad social en el pa\u00eds de la UE donde tiene su sede la empresa que lo env\u00eda. Esto garantiza la exenci\u00f3n del pago de las cotizaciones a la seguridad social en el pa\u00eds de acogida.<\/p>&#13;\n&#13;\n<h3 id=\"h-vat-registration-and-security-deposit\" class=\"wp-block-heading\">Registro del IVA y dep\u00f3sito de garant\u00eda<\/h3>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Las empresas deben registrarse a efectos del IVA en Suiza si:<\/p>&#13;\n\r\n<ul class=\"wp-block-list\">&#13;\n<li>Desplazan trabajadores y prestan servicios en Suiza;<\/li>&#13;\n\r\n\r\n&#13;\n<li>Generan un volumen de negocio global superior a 100.000 CHF por a\u00f1o natural.<\/li>&#13;\n<\/ul>\r\n&#13;\n<p class=\"wp-block-paragraph\">Adem\u00e1s, dependiendo del cant\u00f3n y del sector espec\u00edfico (convenios colectivos), la empresa puede tener que pagar un dep\u00f3sito de seguridad antes de entrar y empezar a trabajar en Suiza. Este dep\u00f3sito sirve como garant\u00eda para cubrir las sanciones contractuales, los costes de inspecci\u00f3n y las contribuciones al Fondo Mixto.<\/p>&#13;\n&#13;\n<h2 id=\"h-residence-permit-for-assignments-exceeding-90-days\" class=\"wp-block-heading\">Permiso de residencia para asignaciones superiores a 90 d\u00edas<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">El procedimiento de notificaci\u00f3n descrito en el apartado anterior no se aplica a las misiones superiores a 90 d\u00edas por a\u00f1o civil. En tales casos, las empresas deben solicitar un permiso de residencia para sus trabajadores en Suiza. Sin embargo, su expedici\u00f3n no es un derecho. La autorizaci\u00f3n est\u00e1 regulada por la <strong>Ley Federal sobre Extranjer\u00eda e Integraci\u00f3n (FNIA)<\/strong>. Las estancias temporales para la prestaci\u00f3n transfronteriza de servicios que superen los 90 d\u00edas laborables por a\u00f1o natural est\u00e1n sujetas a controles del mercado laboral, entre otros:<\/p>&#13;\n\r\n<ul class=\"wp-block-list\">&#13;\n<li>Inter\u00e9s econ\u00f3mico general de Suiza,<\/li>&#13;\n\r\n\r\n&#13;\n<li>Control de las condiciones salariales y laborales,<\/li>&#13;\n\r\n\r\n&#13;\n<li>Evaluaci\u00f3n de las cualificaciones de los trabajadores.<\/li>&#13;\n<\/ul>\r\n&#13;\n<p class=\"wp-block-paragraph\">Adem\u00e1s, estos permisos est\u00e1n sujetos a cuotas. Las autoridades cantonales especifican que s\u00f3lo los <strong>trabajadores especializados<\/strong> pueden optar a la autorizaci\u00f3n. Los empresarios deben respetar las condiciones salariales y laborales locales habituales en el lugar, la profesi\u00f3n y el sector.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Las empresas pueden solicitar un permiso de residencia incluso antes de agotar la asignaci\u00f3n anual, siempre que quede claro desde el principio que el proyecto durar\u00e1 m\u00e1s de 90 d\u00edas.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Si las autoridades cantonales la conceden, la autorizaci\u00f3n ser\u00e1 v\u00e1lida exclusivamente para un proyecto concreto, durante el periodo y en el lugar de trabajo especificados en la solicitud. En caso de ampliaci\u00f3n de las actividades, las empresas deben presentar una nueva solicitud.<\/p>&#13;\n&#13;\n<h2 id=\"h-how-to-apply-for-a-residence-permit-and-additional-obligations\" class=\"wp-block-heading\">C\u00f3mo solicitar un permiso de residencia y obligaciones adicionales<\/h2>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">La solicitud del permiso de residencia debe presentarse en la Oficina de Migraci\u00f3n o en la Autoridad del Mercado Laboral del cant\u00f3n donde se vaya a ejercer la actividad laboral. El procedimiento no es uniforme en todos los cantones, ya que cada uno tiene autoridad para aplicar sus propias normas. Por ejemplo, el cant\u00f3n de Z\u00farich modific\u00f3 recientemente su proceso de solicitud, exigiendo ahora que s\u00f3lo una persona f\u00edsica o jur\u00eddica domiciliada en Suiza pueda presentar solicitudes de permiso de residencia.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Junto con el formulario de solicitud, debe presentarse documentaci\u00f3n adicional, que incluya, por ejemplo: el contrato\/pedido recibido del cliente suizo, una carta de justificaci\u00f3n de la solicitud, la documentaci\u00f3n personal del empleado (como el contrato de trabajo, CV, diplomas y certificados de cualificaci\u00f3n), etc.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">El plazo de tramitaci\u00f3n de las solicitudes var\u00eda en funci\u00f3n del cant\u00f3n beneficiario y suele oscilar <strong>entre 3 y 6 semanas<\/strong>.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">El proceso de solicitud del permiso de residencia est\u00e1 sujeto al pago de tasas cantonales.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Para estancias superiores a 4 meses (120 d\u00edas), el trabajador debe inscribirse en el <strong>registro civil<\/strong> del municipio de residencia en los <strong>14 d\u00edas siguientes a su entrada en Suiza<\/strong> y antes de empezar a trabajar. Posteriormente, la oficina civil concertar\u00e1 una cita para registrar los datos biom\u00e9tricos en la <strong>Oficina Cantonal de Migraci\u00f3n<\/strong>.<\/p>&#13;\n&#13;\n<p class=\"wp-block-paragraph\">Por \u00faltimo, el trabajador deber\u00e1 recoger su <strong>tarjeta de identidad extranjera<\/strong>, que ser\u00e1 v\u00e1lida durante toda su estancia en Suiza.<\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>Esta gu\u00eda describe los pasos esenciales para estancias en Suiza de m\u00e1s de 90 d\u00edas, incluido c\u00f3mo solicitar el permiso de residencia.<\/p>\n","protected":false},"author":42,"featured_media":192749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_angie_page":false,"page_builder":"","footnotes":""},"categories":[1975],"tags":[],"country":[2267],"container":[6618],"service":[6233],"tag-di-competenza":[5621],"class_list":["post-194530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posting-of-workers-for-provisions-of-services","country-suiza","container-global-mobility-services","service-posting-of-workers-to-eu","tag-di-competenza-team-posting-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas<\/title>\n<meta name=\"description\" content=\"Conozca los requisitos clave para las asignaciones en Suiza de m\u00e1s de 90 d\u00edas, incluidos los permisos de residencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas\" \/>\n<meta property=\"og:description\" content=\"Esta gu\u00eda describe los pasos esenciales para estancias en Suiza de m\u00e1s de 90 d\u00edas, incluido c\u00f3mo solicitar el permiso de residencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-27T11:13:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T10:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federica Giglio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica Giglio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/\"},\"author\":{\"name\":\"Federica Giglio\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/27ac8660a717d84fe06b895778179dc3\"},\"headline\":\"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas\",\"datePublished\":\"2025-03-27T11:13:51+00:00\",\"dateModified\":\"2025-12-12T10:30:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/\"},\"wordCount\":1097,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residence-permit-switzerland.png\",\"articleSection\":[\"Posting of Workers for Provisions of Services\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/\",\"name\":\"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residence-permit-switzerland.png\",\"datePublished\":\"2025-03-27T11:13:51+00:00\",\"dateModified\":\"2025-12-12T10:30:54+00:00\",\"description\":\"Conozca los requisitos clave para las asignaciones en Suiza de m\u00e1s de 90 d\u00edas, incluidos los permisos de residencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residence-permit-switzerland.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residence-permit-switzerland.png\",\"width\":1920,\"height\":1080,\"caption\":\"Residence permit switzerland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Labour Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/labour-law\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Posting of Workers for Provisions of Services\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/labour-law\\\/posting-of-workers-for-provisions-of-services\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/27ac8660a717d84fe06b895778179dc3\",\"name\":\"Federica Giglio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g\",\"caption\":\"Federica Giglio\"},\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/author\\\/federica-giglio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas","description":"Conozca los requisitos clave para las asignaciones en Suiza de m\u00e1s de 90 d\u00edas, incluidos los permisos de residencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/","og_locale":"es_ES","og_type":"article","og_title":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas","og_description":"Esta gu\u00eda describe los pasos esenciales para estancias en Suiza de m\u00e1s de 90 d\u00edas, incluido c\u00f3mo solicitar el permiso de residencia.","og_url":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_published_time":"2025-03-27T11:13:51+00:00","article_modified_time":"2025-12-12T10:30:54+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland-1024x576.png","type":"image\/png"}],"author":"Federica Giglio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Federica Giglio","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/"},"author":{"name":"Federica Giglio","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/27ac8660a717d84fe06b895778179dc3"},"headline":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas","datePublished":"2025-03-27T11:13:51+00:00","dateModified":"2025-12-12T10:30:54+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/"},"wordCount":1097,"publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland.png","articleSection":["Posting of Workers for Provisions of Services"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/","url":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/","name":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland.png","datePublished":"2025-03-27T11:13:51+00:00","dateModified":"2025-12-12T10:30:54+00:00","description":"Conozca los requisitos clave para las asignaciones en Suiza de m\u00e1s de 90 d\u00edas, incluidos los permisos de residencia.","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/03\/residence-permit-switzerland.png","width":1920,"height":1080,"caption":"Residence permit switzerland"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/es\/permiso-de-residencia-para-desplazamiento-a-suiza-superior-a-90-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/es\/"},{"@type":"ListItem","position":2,"name":"Labour Law","item":"https:\/\/arlettipartners.com\/es\/category\/labour-law\/"},{"@type":"ListItem","position":3,"name":"Posting of Workers for Provisions of Services","item":"https:\/\/arlettipartners.com\/es\/category\/labour-law\/posting-of-workers-for-provisions-of-services\/"},{"@type":"ListItem","position":4,"name":"Permiso de Residencia para Desplazamiento a Suiza superior a 90 d\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/es\/#website","url":"https:\/\/arlettipartners.com\/es\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/es\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/27ac8660a717d84fe06b895778179dc3","name":"Federica Giglio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58d2371f145ee174d6fff3977edb97c4a4d3e8ed422be5669eb710ace7976c2d?s=96&d=mm&r=g","caption":"Federica Giglio"},"url":"https:\/\/arlettipartners.com\/es\/author\/federica-giglio\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/194530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/comments?post=194530"}],"version-history":[{"count":2,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/194530\/revisions"}],"predecessor-version":[{"id":223666,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/194530\/revisions\/223666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media\/192749"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media?parent=194530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/categories?post=194530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tags?post=194530"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/country?post=194530"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/container?post=194530"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/service?post=194530"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tag-di-competenza?post=194530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}