{"id":190090,"date":"2022-05-10T12:24:43","date_gmt":"2022-05-10T10:24:43","guid":{"rendered":"https:\/\/arlettipartners.com\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/"},"modified":"2025-03-04T12:49:52","modified_gmt":"2025-03-04T11:49:52","slug":"practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana","status":"publish","type":"post","link":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/","title":{"rendered":"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a"},"content":{"rendered":"\n<p class=\"has-text-align-left\">Las reglas aplicadas por Emilia-Roma\u00f1a con respecto a las pasant\u00edas en Italia para ciudadanos no UE siguen las directrices aprobadas en 2014 por el acuerdo entre el Gobierno italiano, las regiones italianas y las provincias aut\u00f3nomas de Trento y Bolzano (<em>Accordo tra Governo, le Regioni e le Province Autonome di Trento e Bolzano<\/em>).<\/p>\n\n<p class=\"has-text-align-left\">Posteriormente, cada regi\u00f3n italiana estableci\u00f3 reglas espec\u00edficas para la transposici\u00f3n de estas directrices, las cuales fueron aprobadas en 2017 por la \u00abConferencia permanente para las relaciones entre el Estado italiano, las regiones y las provincias aut\u00f3nomas de Trento y Bolzano\u00bb.\u00a0<\/p>\n\n<p class=\"has-text-align-left\">Emilia-Roma\u00f1a implement\u00f3 estas directrices en 2020, con algunas modificaciones.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"rules\">Reglas de entrada en Italia para pasant\u00edas desde pa\u00edses no UE<\/h2>\n\n<p class=\"has-text-align-left\">Para ingresar a Italia, los ciudadanos no UE que deseen realizar una pasant\u00eda deben <a href=\"https:\/\/arlettipartners.com\/italian-internship-visa\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">solicitar un visado de pasant\u00eda\/estudio<\/span><\/a> en la representaci\u00f3n italiana en su pa\u00eds de residencia.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-left\"><em>Para presentar la solicitud, es necesario presentar la redacci\u00f3n del proyecto de formaci\u00f3n.<\/em><\/p>\n<\/blockquote>\n\n<p class=\"has-text-align-left\">Debe tener en cuenta que la concesi\u00f3n del visado est\u00e1 sujeta a un cupo (una cantidad m\u00e1xima establecida) establecido por el Gobierno italiano con car\u00e1cter trienal.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"issue\">\u00bfCu\u00e1nto tiempo se tarda en obtener un visado de pasant\u00eda en Italia?<\/h3>\n\n<p class=\"has-text-align-left\">El visado se concede en un plazo m\u00e1ximo de 90 d\u00edas a partir de la fecha de la solicitud. <\/p>\n\n<h3 class=\"wp-block-heading\" id=\"enter\">Qu\u00e9 hacer una vez llegado a Italia<\/h3>\n\n<p class=\"has-text-align-left\">Despu\u00e9s de entrar en Italia con el visado de entrada, el solicitante dispone de 8 d\u00edas para solicitar un <strong>permiso de residencia<\/strong> para estudio\/pasant\u00eda present\u00e1ndose personalmente en la Oficina de Inmigraci\u00f3n del lugar donde desea residir.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"applicants\">Candidatos no UE para una pasant\u00eda en Bolonia o en Emilia-Roma\u00f1a<\/h2>\n\n<p class=\"has-text-align-left\">Los candidatos para una pasant\u00eda en Emilia-Roma\u00f1a deben ser ciudadanos no UE que hayan seguido una formaci\u00f3n profesional o educativa en su pa\u00eds de origen y deseen completarla con una pasant\u00eda en Italia. <\/p>\n\n<p class=\"has-text-align-left\">Esto tambi\u00e9n incluye a personas desempleadas. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"terms\">Pr\u00e1ctica en Italia: Condiciones de la pr\u00e1ctica<\/h2>\n\n<p class=\"has-text-align-left\">La pasant\u00eda para ciudadanos no UE debe durar al menos 91 d\u00edas y no puede superar los 12 meses, incluidas las posibles extensiones. <\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-left\"><em>La pasant\u00eda debe activarse dentro de los 8 d\u00edas siguientes a la solicitud de entrada en Italia (y no en los 15 d\u00edas como se prev\u00e9 en la legislaci\u00f3n italiana).<\/em><\/p>\n<\/blockquote>\n\n<h3 class=\"wp-block-heading\" id=\"workpermit\">\u00bfEs posible obtener un permiso de trabajo con la pasant\u00eda?<\/h3>\n\n<p class=\"has-text-align-left\">Al final de la pasant\u00eda, <strong>el permiso de residencia para estudio\/pr\u00e1ctica puede ser convertido en un permiso de trabajo<\/strong> si un empleador contrata al pasante con un contrato de trabajo v\u00e1lido. Esta conversi\u00f3n est\u00e1 sujeta al n\u00famero de permisos de trabajo que Italia emite cada a\u00f1o seg\u00fan el decreto flussi (cupo de trabajadores extranjeros).<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"interruption\">\u00bfQu\u00e9 ocurre si la pr\u00e1ctica se interrumpe antes de su conclusi\u00f3n normal?<\/h3>\n\n<p class=\"has-text-align-left\">Si una pasant\u00eda se interrumpe antes de la fecha prevista, el pasante debe abandonar el pa\u00eds en los 15 d\u00edas siguientes a la notificaci\u00f3n de suspensi\u00f3n. En este caso, la entidad anfitriona debe cubrir los gastos relacionados con el regreso obligatorio del pasante. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"compensation\">Compensaci\u00f3n por una pasant\u00eda en Bolonia y en Emilia-Roma\u00f1a<\/h2>\n\n<p class=\"has-text-align-left\">El pasante tiene derecho a una compensaci\u00f3n de al menos 450,00 \u20ac por mes (este monto puede variar seg\u00fan la regi\u00f3n donde se realice la pasant\u00eda). <\/p>\n\n<p class=\"has-text-align-left\">El pasante tambi\u00e9n recibe alojamiento y pensi\u00f3n proporcionados por la entidad anfitriona. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"tutoring\">Tutor\u00eda y Certificado de Participaci\u00f3n<\/h2>\n\n<p class=\"has-text-align-left\">Durante la pasant\u00eda, un tutor de la entidad promotora y un tutor de la entidad anfitriona seguir\u00e1n al pasante para que pueda alcanzar los objetivos pedag\u00f3gicos de la pasant\u00eda indicados en el proyecto de formaci\u00f3n. <\/p>\n\n<p class=\"has-text-align-left\">A solicitud, la entidad promotora puede emitir un certificado de participaci\u00f3n al final de la pasant\u00eda (<em>Attestato di partecipazione<\/em>), indicando los resultados obtenidos por el pasante.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"exclusion\">\u00bfExisten casos de exclusi\u00f3n para la pasant\u00eda en Italia o en Bolonia?<\/h2>\n\n<p class=\"has-text-align-left\">No se permiten las pasant\u00edas que impliquen actividades laborales muy simples que no requieran un per\u00edodo de formaci\u00f3n. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre c\u00f3mo solicitar una pr\u00e1ctica en Emilia-Roma\u00f1a y los requisitos para obtener el visado.<\/p>\n","protected":false},"author":31,"featured_media":152998,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1433,1436,1443],"tags":[],"country":[1504],"container":[],"service":[6465],"tag-di-competenza":[5620],"class_list":["post-190090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immigration-law","category-visa-immigration-law","category-work-visa","country-italia-es","service-visa-internship-italy-2","tag-di-competenza-team-im-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pr\u00e1cticas en Italia y Bolonia para ciudadanos no UE<\/title>\n<meta name=\"description\" content=\"Pr\u00e1cticas en Italia: si busca unas pr\u00e1cticas en Bolonia, inf\u00f3rmese sobre las condiciones de solicitud para los ciudadanos extracomunitarios\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo solicitar una pr\u00e1ctica en Emilia-Roma\u00f1a y los requisitos para obtener el visado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T10:24:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T11:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna-1024x549.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sofia Galletti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sofia Galletti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/\"},\"author\":{\"name\":\"Sofia Galletti\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/a389fe5ccd4dc7635e1456ba0444fb6c\"},\"headline\":\"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a\",\"datePublished\":\"2022-05-10T10:24:43+00:00\",\"dateModified\":\"2025-03-04T11:49:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/\"},\"wordCount\":716,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/emilia.romagna.png\",\"articleSection\":[\"Immigration Law\",\"Visa\",\"Work Visa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/\",\"name\":\"Pr\u00e1cticas en Italia y Bolonia para ciudadanos no UE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/emilia.romagna.png\",\"datePublished\":\"2022-05-10T10:24:43+00:00\",\"dateModified\":\"2025-03-04T11:49:52+00:00\",\"description\":\"Pr\u00e1cticas en Italia: si busca unas pr\u00e1cticas en Bolonia, inf\u00f3rmese sobre las condiciones de solicitud para los ciudadanos extracomunitarios\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/emilia.romagna.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/emilia.romagna.png\",\"width\":1400,\"height\":750,\"caption\":\"for internship in Bologna, learn conditions for internship in Italy\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immigration Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/immigration-law\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Visa\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/immigration-law\\\/visa-immigration-law\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Work Visa\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/immigration-law\\\/visa-immigration-law\\\/work-visa\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/a389fe5ccd4dc7635e1456ba0444fb6c\",\"name\":\"Sofia Galletti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g\",\"caption\":\"Sofia Galletti\"},\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/author\\\/sofia-galletti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pr\u00e1cticas en Italia y Bolonia para ciudadanos no UE","description":"Pr\u00e1cticas en Italia: si busca unas pr\u00e1cticas en Bolonia, inf\u00f3rmese sobre las condiciones de solicitud para los ciudadanos extracomunitarios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/","og_locale":"es_ES","og_type":"article","og_title":"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a","og_description":"Descubre c\u00f3mo solicitar una pr\u00e1ctica en Emilia-Roma\u00f1a y los requisitos para obtener el visado.","og_url":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_published_time":"2022-05-10T10:24:43+00:00","article_modified_time":"2025-03-04T11:49:52+00:00","og_image":[{"width":1024,"height":549,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna-1024x549.png","type":"image\/png"}],"author":"Sofia Galletti","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sofia Galletti","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/"},"author":{"name":"Sofia Galletti","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/a389fe5ccd4dc7635e1456ba0444fb6c"},"headline":"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a","datePublished":"2022-05-10T10:24:43+00:00","dateModified":"2025-03-04T11:49:52+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/"},"wordCount":716,"publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna.png","articleSection":["Immigration Law","Visa","Work Visa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/","url":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/","name":"Pr\u00e1cticas en Italia y Bolonia para ciudadanos no UE","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna.png","datePublished":"2022-05-10T10:24:43+00:00","dateModified":"2025-03-04T11:49:52+00:00","description":"Pr\u00e1cticas en Italia: si busca unas pr\u00e1cticas en Bolonia, inf\u00f3rmese sobre las condiciones de solicitud para los ciudadanos extracomunitarios","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/05\/emilia.romagna.png","width":1400,"height":750,"caption":"for internship in Bologna, learn conditions for internship in Italy"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/es\/practicas-en-italia-para-ciudadanos-no-ue-reglas-aplicadas-por-la-region-de-emilia-romana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/es\/"},{"@type":"ListItem","position":2,"name":"Immigration Law","item":"https:\/\/arlettipartners.com\/es\/category\/immigration-law\/"},{"@type":"ListItem","position":3,"name":"Visa","item":"https:\/\/arlettipartners.com\/es\/category\/immigration-law\/visa-immigration-law\/"},{"@type":"ListItem","position":4,"name":"Work Visa","item":"https:\/\/arlettipartners.com\/es\/category\/immigration-law\/visa-immigration-law\/work-visa\/"},{"@type":"ListItem","position":5,"name":"Pr\u00e1cticas en Italia para ciudadanos no UE: reglas aplicadas por la regi\u00f3n de Emilia-Roma\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/es\/#website","url":"https:\/\/arlettipartners.com\/es\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/es\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/a389fe5ccd4dc7635e1456ba0444fb6c","name":"Sofia Galletti","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e0cbe31cacd37256c5678f7d1ac82336b93c52345fefa3e8a627454ff94d04b?s=96&d=mm&r=g","caption":"Sofia Galletti"},"url":"https:\/\/arlettipartners.com\/es\/author\/sofia-galletti\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/190090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/comments?post=190090"}],"version-history":[{"count":0,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/190090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media\/152998"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media?parent=190090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/categories?post=190090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tags?post=190090"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/country?post=190090"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/container?post=190090"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/service?post=190090"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tag-di-competenza?post=190090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}