{"id":178519,"date":"2022-09-08T11:56:50","date_gmt":"2022-09-08T09:56:50","guid":{"rendered":"https:\/\/arlettipartners.com\/desplazamiento-de-trabajadores-a-grecia\/"},"modified":"2024-07-25T11:50:53","modified_gmt":"2024-07-25T09:50:53","slug":"desplazamiento-de-trabajadores-a-grecia","status":"publish","type":"post","link":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/","title":{"rendered":"Desplazamiento de trabajadores a Grecia"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\">La transposici\u00f3n nacional de la <a href=\"https:\/\/arlettipartners.com\/desplazamientos-transnacionales-la-directiva-2014-67-ue\/?lang=es\">Directiva 2014\/67\/UE<\/a> del Parlamento Europeo y del Consejo, de 15 de mayo de 2014, sobre la aplicaci\u00f3n de la Directiva 96\/71\/CE relativa al desplazamiento de trabajadores, se ha implementado en Grecia mediante el Decreto Presidencial Nacional 219\/2000. Este decreto se titula \u201cMedidas de protecci\u00f3n de los trabajadores desplazados a Grecia para realizar un trabajo temporal en el territorio griego en el marco de la prestaci\u00f3n transnacional de servicios\u201d.<\/p>\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Para una visi\u00f3n general de todas las Directivas relacionadas con el desplazamiento, consulta nuestra gu\u00eda sobre las <a href=\"https:\/\/arlettipartners.com\/directivas-ue-sobre-el-desplazamiento-de-trabajadores-en-europa-analisis-completo\/?lang=es\">Directivas de la UE sobre el desplazamiento de trabajadores.<\/a><\/p>\n<\/blockquote>\n\n<h2 class=\"wp-block-heading\" id=\"obligations\">Obligaciones preliminares en el desplazamiento de trabajadores a Grecia<\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">Una empresa extranjera que desplace trabajadores debe enviar una <a href=\"https:\/\/arlettipartners.com\/declaracion-de-desplazamiento\/?lang=es\">declaraci\u00f3n preliminar de desplazamiento<\/a> por escrito, en griego o en ingl\u00e9s, antes del inicio de la prestaci\u00f3n de servicios. El documento debe ser enviado al departamento competente de la Inspecci\u00f3n de Trabajo en territorio griego.<\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">Cada trabajador empleado debe ser notificado. Sin embargo, existen algunas excepciones. Por ejemplo, las compa\u00f1\u00edas de navegaci\u00f3n que desplacen personal mar\u00edtimo est\u00e1n exentas de esta obligaci\u00f3n. <\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">Al redactar los documentos esenciales para el desplazamiento a Grecia, es importante tener en cuenta que algunos datos son obligatorios. Estos incluyen: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Informaci\u00f3n sobre la empresa desplazante, direcci\u00f3n y sede legal; <\/li>\n\n\n\n<li>Datos del representante legal de la empresa desplazante; <\/li>\n\n\n\n<li>Datos del representante legal de la empresa de acogida en Grecia; <\/li>\n\n\n\n<li>Direcci\u00f3n del lugar de trabajo donde los trabajadores desplazados prestar\u00e1n servicio; <\/li>\n\n\n\n<li>Datos de los trabajadores desplazados; <\/li>\n\n\n\n<li>Fechas de inicio y fin del periodo del desplazamiento. <\/li>\n<\/ul>\n\n<p class=\"has-text-align-left wp-block-paragraph\">En caso de modificaci\u00f3n de los datos en la declaraci\u00f3n de desplazamiento, la empresa desplazante deber\u00e1 enviar una nueva notificaci\u00f3n con la modificaci\u00f3n correspondiente a m\u00e1s tardar dentro de los 15 d\u00edas posteriores a la fecha de la modificaci\u00f3n. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"conditions\">Condiciones laborales y salariales en Grecia<\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">La Directiva 957\/2018\/UE sobre la armonizaci\u00f3n salarial y las condiciones laborales no ha sido transpuesta en Grecia. Por este motivo, la normativa de referencia sigue siendo la Directiva 96\/71\/CE. Su equivalente nacional es el Decreto Presidencial griego del 31 de agosto de 2000. <\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">La semana laboral est\u00e1ndar en Grecia consta de 40 horas. Sin embargo, incluyendo las horas extras, se permite trabajar hasta un m\u00e1ximo de 48 horas a la semana. <\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">El Decreto Presidencial 190\/2000 establece que los salarios y remuneraciones est\u00e1n determinados por el C\u00f3digo del Trabajo griego (leyes, decretos y decisiones ministeriales) y los convenios colectivos. De acuerdo con la Directiva 96\/71\/CE, implementada por la Directiva 2018\/957\/UE, un trabajador desplazado a un Estado miembro de la Uni\u00f3n Europea debe beneficiarse de las condiciones m\u00e1s favorables entre las griegas y las del Estado en el que est\u00e1 habitualmente empleado. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"documents\">Archivo de documentos relacionados con el desplazamiento a Grecia<\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">En Grecia, el lugar de trabajo se considera el lugar donde toda la documentaci\u00f3n relativa al desplazamiento debe ser mantenida y conservada. Los documentos m\u00e1s importantes suelen ser: <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Contrato de trabajo (o documento equivalente); <\/li>\n\n\n\n<li>Reciente n\u00f3mina del trabajador desplazado a Grecia; <\/li>\n\n\n\n<li>Registro de horas trabajadas; <\/li>\n\n\n\n<li>Comprobante de pago del salario. <\/li>\n<\/ul>\n\n<p class=\"has-text-align-left wp-block-paragraph\">En caso de inspecci\u00f3n, el empleador deber\u00e1 proporcionar a la autoridad competente todos los documentos en griego o ingl\u00e9s. Estos documentos deben ser proporcionados dentro de los 15 d\u00edas posteriores a la recepci\u00f3n de la solicitud de las autoridades. En cualquier caso, las autoridades griegas pueden realizar una inspecci\u00f3n hasta un m\u00e1ximo de dos a\u00f1os despu\u00e9s del final del desplazamiento. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"noneu\">Trabajadores extracomunitarios en Grecia <\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">En general, un ciudadano de un tercer pa\u00eds que posea un permiso de residencia en otro Estado miembro puede ingresar a Grecia, pero no puede realizar actividades adicionales. Los trabajadores extracomunitarios no pueden trabajar en Grecia a menos que posean un visado\/permiso de trabajo griego espec\u00edfico. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"socialsecurity\">Seguridad social en Grecia<\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">De acuerdo con el Reglamento Europeo 883\/2004, los trabajadores desplazados a Grecia siguen sujetos a la seguridad social del Estado miembro donde est\u00e1 establecido su empleador. <\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">La empresa desplazante deber\u00e1 solicitar el <a href=\"https:\/\/arlettipartners.com\/modelo-a1\/?lang=es\">Formulario A1<\/a>. La entidad provincial de referencia emitir\u00e1 el documento una vez que se hayan completado todos los datos necesarios.<\/p>\n\n<p class=\"has-text-align-left wp-block-paragraph\">El Formulario A1 puede tener una duraci\u00f3n m\u00e1xima de 24 meses. Adem\u00e1s, el trabajador debe tener siempre este documento durante todo el periodo de su desplazamiento. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"penalties\">Sanciones en caso de incumplimiento de las obligaciones griegas durante el desplazamiento de trabajadores<\/h2>\n\n<p class=\"has-text-align-left wp-block-paragraph\">Un empleador que no cumpla con las obligaciones establecidas por el C\u00f3digo del Trabajo griego puede ser sancionado con medidas tanto administrativas como penales. <\/p>\n\n<h3 class=\"wp-block-heading\">Sanciones administrativas<\/h3>\n\n<p class=\"has-text-align-left wp-block-paragraph\">De acuerdo con los Art\u00edculos 16 y 17 de la Ley 2639\/1998, un empleador que no cumpla con los t\u00e9rminos y condiciones establecidos por el C\u00f3digo del Trabajo puede ser sancionado con una multa que var\u00eda entre \u20ac1,000 y \u20ac30,000 por cada incumplimiento. <\/p>\n\n<h3 class=\"wp-block-heading\">Sanciones penales<\/h3>\n\n<p class=\"has-text-align-left wp-block-paragraph\">Por otro lado, el incumplimiento de los t\u00e9rminos y condiciones relacionados con el horario de trabajo, la remuneraci\u00f3n, etc., es punible con al menos 6 meses de prisi\u00f3n, una multa de \u20ac900, o ambas sanciones. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todas las directrices relativas a las obligaciones requeridas antes, durante y despu\u00e9s del desplazamiento de sus empleados a Grecia. <\/p>\n","protected":false},"author":44,"featured_media":153029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_angie_page":false,"page_builder":"","footnotes":""},"categories":[1975],"tags":[],"country":[1571],"container":[6598],"service":[6233],"tag-di-competenza":[5621],"class_list":["post-178519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-posting-of-workers-for-provisions-of-services","country-grecia-es","container-global-mobility-services","service-posting-of-workers-to-eu","tag-di-competenza-team-posting-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Desplazamiento trabajadores a Grecia: normativa y obligaciones<\/title>\n<meta name=\"description\" content=\"Descubre la normativa nacional en materia de desplazamiento de trabajadores a Grecia y todas las obligaciones y requisitos necesarios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desplazamiento de trabajadores a Grecia\" \/>\n<meta property=\"og:description\" content=\"Todas las directrices relativas a las obligaciones requeridas antes, durante y despu\u00e9s del desplazamiento de sus empleados a Grecia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T09:56:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T09:50:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federica Primiceri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica Primiceri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/\"},\"author\":{\"name\":\"Federica Primiceri\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/e2533e6d1d72ba1513df654387b61cb9\"},\"headline\":\"Desplazamiento de trabajadores a Grecia\",\"datePublished\":\"2022-09-08T09:56:50+00:00\",\"dateModified\":\"2024-07-25T09:50:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/\"},\"wordCount\":853,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/posting.workers.greece.png\",\"articleSection\":[\"Posting of Workers for Provisions of Services\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/\",\"name\":\"Desplazamiento trabajadores a Grecia: normativa y obligaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/posting.workers.greece.png\",\"datePublished\":\"2022-09-08T09:56:50+00:00\",\"dateModified\":\"2024-07-25T09:50:53+00:00\",\"description\":\"Descubre la normativa nacional en materia de desplazamiento de trabajadores a Grecia y todas las obligaciones y requisitos necesarios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/posting.workers.greece.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/posting.workers.greece.png\",\"width\":1400,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/desplazamiento-de-trabajadores-a-grecia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Labour Law\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/labour-law\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Posting of Workers for Provisions of Services\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/category\\\/labour-law\\\/posting-of-workers-for-provisions-of-services\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Desplazamiento de trabajadores a Grecia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/#\\\/schema\\\/person\\\/e2533e6d1d72ba1513df654387b61cb9\",\"name\":\"Federica Primiceri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g\",\"caption\":\"Federica Primiceri\"},\"url\":\"https:\\\/\\\/arlettipartners.com\\\/es\\\/author\\\/federica-primiceri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Desplazamiento trabajadores a Grecia: normativa y obligaciones","description":"Descubre la normativa nacional en materia de desplazamiento de trabajadores a Grecia y todas las obligaciones y requisitos necesarios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/","og_locale":"es_ES","og_type":"article","og_title":"Desplazamiento de trabajadores a Grecia","og_description":"Todas las directrices relativas a las obligaciones requeridas antes, durante y despu\u00e9s del desplazamiento de sus empleados a Grecia.","og_url":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_published_time":"2022-09-08T09:56:50+00:00","article_modified_time":"2024-07-25T09:50:53+00:00","og_image":[{"width":1400,"height":750,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png","type":"image\/png"}],"author":"Federica Primiceri","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Federica Primiceri","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/"},"author":{"name":"Federica Primiceri","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/e2533e6d1d72ba1513df654387b61cb9"},"headline":"Desplazamiento de trabajadores a Grecia","datePublished":"2022-09-08T09:56:50+00:00","dateModified":"2024-07-25T09:50:53+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/"},"wordCount":853,"publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png","articleSection":["Posting of Workers for Provisions of Services"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/","url":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/","name":"Desplazamiento trabajadores a Grecia: normativa y obligaciones","isPartOf":{"@id":"https:\/\/arlettipartners.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png","datePublished":"2022-09-08T09:56:50+00:00","dateModified":"2024-07-25T09:50:53+00:00","description":"Descubre la normativa nacional en materia de desplazamiento de trabajadores a Grecia y todas las obligaciones y requisitos necesarios.","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/08\/posting.workers.greece.png","width":1400,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/es\/desplazamiento-de-trabajadores-a-grecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/es\/"},{"@type":"ListItem","position":2,"name":"Labour Law","item":"https:\/\/arlettipartners.com\/es\/category\/labour-law\/"},{"@type":"ListItem","position":3,"name":"Posting of Workers for Provisions of Services","item":"https:\/\/arlettipartners.com\/es\/category\/labour-law\/posting-of-workers-for-provisions-of-services\/"},{"@type":"ListItem","position":4,"name":"Desplazamiento de trabajadores a Grecia"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/es\/#website","url":"https:\/\/arlettipartners.com\/es\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/es\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/es\/#\/schema\/person\/e2533e6d1d72ba1513df654387b61cb9","name":"Federica Primiceri","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3cca442a738c21760438124e7f804820dedb61065c834b907e1027b079b8af3?s=96&d=mm&r=g","caption":"Federica Primiceri"},"url":"https:\/\/arlettipartners.com\/es\/author\/federica-primiceri\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/178519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/comments?post=178519"}],"version-history":[{"count":0,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/posts\/178519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media\/153029"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/media?parent=178519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/categories?post=178519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tags?post=178519"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/country?post=178519"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/container?post=178519"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/service?post=178519"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/es\/wp-json\/wp\/v2\/tag-di-competenza?post=178519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}