{"id":186204,"date":"2025-01-21T09:47:11","date_gmt":"2025-01-21T08:47:11","guid":{"rendered":"https:\/\/arlettipartners.com\/die-finnische-steuernummer-und-die-valtti-karte\/"},"modified":"2025-01-24T08:55:05","modified_gmt":"2025-01-24T07:55:05","slug":"die-finnische-steuernummer-und-die-valtti-karte","status":"publish","type":"post","link":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/","title":{"rendered":"Die finnische Steuernummer und die Valtti-Karte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Unternehmen und Selbst\u00e4ndige, die auf Baustellen\/Schiffswerften in Finnland t\u00e4tig sind, m\u00fcssen eine <strong>finnische Steuernummer<\/strong> und eine Identifikationskarte (<strong>Valtti-Karte<\/strong>) beantragen, um berechtigt zu sein, den Arbeitsplatz zu betreten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Artikel werden wir die zus\u00e4tzlichen Verpflichtungen f\u00fcr Arbeitgeber analysieren, die T\u00e4tigkeiten an diesen Arten von Arbeitspl\u00e4tzen in Finnland aus\u00fcben.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>F\u00fcr weitere Details zu allen Verpflichtungen lesen Sie unseren Artikel \u00fcber die <a href=\"https:\/\/arlettipartners.com\/entsendung-von-arbeitnehmern-nach-finnland\/?lang=de\">Entsendung von Arbeitnehmern nach Finnland<\/a>.<\/em><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-baustellen-schiffswerften-in-finnland\">Baustellen\/Schiffswerften in Finnland<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In Finnland wird die Kategorisierung und die Definition einer Baustelle durch die <a href=\"https:\/\/www.finlex.fi\/en\/laki\/kaannokset\/2009\/en20090205_20090205.pdf\" target=\"_blank\" rel=\"noopener\">Verordnung \u00fcber die Sicherheit von Bauarbeiten 205\/2009, Abschnitt 1<\/a> (<em>asetus rakennusty\u00f6n turvallisuudesta<\/em>, 205\/2009), geregelt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gem\u00e4\u00df der Verordnung kann eine <strong>Baustelle<\/strong> sein:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arbeiten im Zusammenhang mit Neubauten;<\/li>\n\n\n\n<li>Wartung oder Renovierung von Geb\u00e4uden oder anderen Bauwerken (einschlie\u00dflich auf See);<\/li>\n\n\n\n<li>Installations-, Abbruch-, Tiefbau- und Bauplanungsarbeiten.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus gilt die Verordnung auch f\u00fcr Vorbereitungs- und Planungsarbeiten im Zusammenhang mit den oben genannten T\u00e4tigkeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abschnitt 52c des <a href=\"https:\/\/www.finlex.fi\/sv\/laki\/kaannokset\/1958\/en19580299_19990203.pdf\" target=\"_blank\" rel=\"noopener\">Arbeitsschutzgesetzes<\/a> definiert, was eine <strong>Schiffswerft<\/strong> ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Schiffswerft ist ein gemeinsamer Arbeitsplatz f\u00fcr:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reparatur oder Bau von Handelsschiffen,<\/li>\n\n\n\n<li>Reparatur oder Bau von Schiffen, die von \u00f6ffentlichen Beh\u00f6rden genutzt werden, oder<\/li>\n\n\n\n<li>Reparatur oder Bau von Schiffen, die l\u00e4nger als 24 Meter sind.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Abschnitt 49 desselben Gesetzes kl\u00e4rt die Definition eines <strong>gemeinsamen Arbeitsplatzes<\/strong>, der ein Arbeitsplatz ist, der einem einzigen Arbeitgeber geh\u00f6rt, an dem jedoch andere Unternehmen\/Selbst\u00e4ndige gleichzeitig oder nacheinander ihre T\u00e4tigkeiten aus\u00fcben. Dies kann die Gesundheit und Sicherheit von Arbeitnehmern verschiedener Unternehmen beeinflussen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-finnische-steuernummer\">Die finnische Steuernummer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Falle der grenz\u00fcberschreitenden Erbringung von Dienstleistungen an einem der beiden genannten Arbeitsorte reicht es nicht aus, die <a href=\"https:\/\/arlettipartners.com\/entsendemeldung\/?lang=de\">Entsendemeldung<\/a> einzureichen, einen Vertreter vor Ort zu benennen, die <a href=\"https:\/\/arlettipartners.com\/a1-bescheinigung-definitionen-relevanz-und-anwendung-der-verordnung-883-2004-im-bereich-der-sozialen-sicherheit-von-entsandten-arbeitnehmern\/?lang=de\">A1-Bescheinigung<\/a> zu besitzen und die Arbeits-, Sicherheits- und Lohnbedingungen vor Ort einzuhalten, um den lokalen Vorschriften zu entsprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tats\u00e4chlich m\u00fcssen die Arbeiter ein <strong>Identifikationsdokument<\/strong> (Valtti-Karte) und eine<strong> finnische Steuernummer<\/strong> besitzen. Diese Anforderung wurde speziell eingef\u00fchrt, um Schattenwirtschaft oder Schwarzarbeit zu bek\u00e4mpfen. Zudem ist sie auch wesentlich, um das Personal auf Baustellen\/Schiffswerften sowie die Steuerkonformit\u00e4t der Arbeiter zu \u00fcberwachen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verpflichtung zur Eintragung in das finnische Steuerregister und zum Besitz einer finnischen Steuernummer gilt seit dem 01.07.2022. Diese Anforderung ergibt sich aus dem Gesetz \u00fcber die Steuernummer und das Steuerregister (<em><a href=\"https:\/\/www.finlex.fi\/fi\/laki\/alkup\/2021\/20210473\" target=\"_blank\" rel=\"noopener\">Laki veronumerosta ja veronumerorekisterist\u00e4<\/a><\/em>, 473\/2021) und wird auch im Arbeitsschutzgesetz standardisiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>finnische <\/strong><strong>Steuernummer<\/strong> ist ein 12-stelliger Code, den finnische B\u00fcrger bei der Geburt zusammen mit einer Steuer-ID erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">B\u00fcrger, die nicht in Finnland ans\u00e4ssig sind, m\u00fcssen dagegen einen Antrag bei der Steuerverwaltung stellen, um beides zu erhalten. Das <strong>Antragsverfahren<\/strong> muss pers\u00f6nlich vom Antragsteller durchgef\u00fchrt werden, der Profilformulare mit folgenden Angaben einreichen muss:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pers\u00f6nliche Daten des Antragstellers,<\/li>\n\n\n\n<li>Gehaltsinformationen des Antragstellers,<\/li>\n\n\n\n<li>Informationen \u00fcber die T\u00e4tigkeit in Finnland,<\/li>\n\n\n\n<li>Informationen \u00fcber die Dauer der T\u00e4tigkeit in Finnland.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Steuerverwaltung sendet die Steuer-ID mit der enthaltenen Steuernummer per E-Mail einige Tage nach dem Termin. Bearbeitungszeiten k\u00f6nnen variieren, daher ist es notwendig, den Termin im Voraus vor dem geplanten Arbeitsbeginn zu vereinbaren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-die-valtti-karte-und-die-entsendemeldung\">Die Valtti-Karte und die Entsendemeldung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sobald der Arbeitnehmer und\/oder Selbst\u00e4ndige die<strong> Steuer-ID<\/strong> (die auch Informationen \u00fcber die Steuernummer enth\u00e4lt) erhalten hat, muss er die Identifikationskarte (<strong>Valtti-Karte<\/strong>) beantragen, um den Arbeitsplatz zu betreten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Ausweis muss gem\u00e4\u00df den Bestimmungen der Abschnitte 52a und 52c des Arbeitsschutzgesetzes folgende Informationen enthalten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vollst\u00e4ndiger Name des Arbeitnehmers,<\/li>\n\n\n\n<li>Foto des Arbeitnehmers,<\/li>\n\n\n\n<li>Name des Arbeitgebers (falls angestellt),<\/li>\n\n\n\n<li>Finnische Steuernummer,<\/li>\n\n\n\n<li>Art des Arbeitnehmers (Arbeitnehmer oder Selbst\u00e4ndiger).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die physische Valtti-Karte wird an die w\u00e4hrend des Antragsprozesses angegebene Adresse gesendet. Ein vorl\u00e4ufiges Zertifikat im PDF-Format ist jedoch sofort verf\u00fcgbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobald der Arbeiter das Dokument besitzt und die Meldung \u00fcber die grenz\u00fcberschreitende Dienstleistungserbringung im finnischen nationalen Portal abgeschlossen hat (in dem auch die Steuernummer des Arbeitnehmers angegeben werden muss), kann er die R\u00e4umlichkeiten betreten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-zusatzliche-meldepflichten\">Zus\u00e4tzliche Meldepflichten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zus\u00e4tzlich zu den oben beschriebenen Verpflichtungen muss der Auftraggeber f\u00fcr die Bauarbeiten bis sp\u00e4testens zum 5. des Folgemonats einen <strong>Monatsbericht<\/strong> \u00fcber die am Arbeitsplatz durchgef\u00fchrten Arbeiten einreichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das<strong> Gesetz \u00fcber die Beurteilungsverfahren<\/strong> (\u00a715b, \u00a715c und \u00a715d) f\u00fchrt die Meldepflicht auf Baustellen ein. Die Verpflichtung wird haupts\u00e4chlich f\u00fcr Steuerzwecke und zur Bek\u00e4mpfung von Schwarzarbeit eingef\u00fchrt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der K\u00e4ufer der Bauarbeiten muss die <strong>zust\u00e4ndigen Beh\u00f6rden<\/strong> \u00fcber die Dienstleistungsunternehmen in folgenden F\u00e4llen <strong>informieren<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Das Subunternehmen hat dem K\u00e4ufer eine Bauleistung erbracht (\u00a7 31.3.1 MwSt-Gesetz),<\/li>\n\n\n\n<li>Das Subunternehmen hat Ger\u00fcste f\u00fcr Bauarbeiten errichtet oder abgebaut, oder<\/li>\n\n\n\n<li>Das Subunternehmen hat Personal f\u00fcr die oben genannten Arbeiten bereitgestellt.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Aus diesem Grund berichtet der Kunde \u00fcber die T\u00e4tigkeiten seiner Subunternehmer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Falle einer <strong>Subunternehmerkette<\/strong> hingegen muss jedes Unternehmen, das eigene Subunternehmer hat, \u00fcber die Aktivit\u00e4ten seiner Lieferanten berichten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Planungs- und \u00dcberwachungsarbeiten sind von der Meldepflicht ausgenommen, es sei denn, sie werden von dem Unternehmen durchgef\u00fchrt, das andere Bauleistungen erbringt, die der gleichen Verpflichtung unterliegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Auftraggeber muss den Bericht einreichen oder sich direkt an die Steuerverwaltung wenden, um folgende <strong>Daten<\/strong> bereitzustellen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Allgemeine Informationen \u00fcber den Subunternehmer,<\/li>\n\n\n\n<li>Informationen \u00fcber die Baustelle,<\/li>\n\n\n\n<li>Informationen \u00fcber den Auftraggeber und die entsprechende Kontaktperson,<\/li>\n\n\n\n<li>Vertragswert in Euro f\u00fcr jeden Monatsbericht,<\/li>\n\n\n\n<li>Dauer des Vertrags,<\/li>\n\n\n\n<li>Kategorie oder Art des Vertrags\/der Vereinbarung zwischen den Parteien,<\/li>\n\n\n\n<li>Anwendbarkeit oder Nichtanwendbarkeit der Umkehrung der Steuerschuldnerschaft (Reverse Charge) f\u00fcr die Mehrwertsteuer.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>In Finnland ist die Einhaltung der Vorschriften f\u00fcr Bau- und Werftarbeiten von entscheidender Bedeutung. In diesem Zusammenhang spielen die finnische Steuernummer und die Valtti-Karte eine zentrale Rolle.<\/p>\n","protected":false},"author":46,"featured_media":186007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_angie_page":false,"page_builder":"","footnotes":""},"categories":[1622,1696],"tags":[],"country":[2015],"container":[6615,6598],"service":[6709,6713],"tag-di-competenza":[5613],"class_list":["post-186204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administrative-fulfilments","country-finnland","container-global-mobility-services","service-protection-of-health-and-safety-at-work-in-the-eu-eng","tag-di-competenza-team-posting-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die finnische Steuernummer und die Valtti-Karte - Arletti Partners<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber die Beantragung der Valtti-Karte und der finnischen Steuernummer f\u00fcr Arbeitnehmer, die nach Finnland entsandt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die finnische Steuernummer und die Valtti-Karte\" \/>\n<meta property=\"og:description\" content=\"In Finnland ist die Einhaltung der Vorschriften f\u00fcr Bau- und Werftarbeiten von entscheidender Bedeutung. In diesem Zusammenhang spielen die finnische Steuernummer und die Valtti-Karte eine zentrale Rolle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/\" \/>\n<meta property=\"og:site_name\" content=\"Arletti Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArlettiPartners\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T08:47:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-24T07:55:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salvatore La Rocca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salvatore La Rocca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/\"},\"author\":{\"name\":\"Salvatore La Rocca\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#\\\/schema\\\/person\\\/a592359405c2816205501785c0543c7c\"},\"headline\":\"Die finnische Steuernummer und die Valtti-Karte\",\"datePublished\":\"2025-01-21T08:47:11+00:00\",\"dateModified\":\"2025-01-24T07:55:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/\"},\"wordCount\":878,\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Progetto-senza-titolo-4-1.png\",\"articleSection\":[\"Administrative Fulfilments\",\"Administrative Fulfilments\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/\",\"name\":\"Die finnische Steuernummer und die Valtti-Karte - Arletti Partners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Progetto-senza-titolo-4-1.png\",\"datePublished\":\"2025-01-21T08:47:11+00:00\",\"dateModified\":\"2025-01-24T07:55:05+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber die Beantragung der Valtti-Karte und der finnischen Steuernummer f\u00fcr Arbeitnehmer, die nach Finnland entsandt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Progetto-senza-titolo-4-1.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Progetto-senza-titolo-4-1.png\",\"width\":1300,\"height\":700,\"caption\":\"valtti card and finnish tax number\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/die-finnische-steuernummer-und-die-valtti-karte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Health &amp; Safety at Work for Employees\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/category\\\/health-safety-at-work-for-employees\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Administrative Fulfilments\",\"item\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/category\\\/health-safety-at-work-for-employees\\\/administrative-fulfilments\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Die finnische Steuernummer und die Valtti-Karte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/\",\"name\":\"Arletti Partners\",\"description\":\"Tax Advisors and Global Mobility Specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#organization\",\"name\":\"Arletti & Partners\",\"alternateName\":\"Studio Arletti\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"contentUrl\":\"https:\\\/\\\/arlettipartners.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-logo.png.nuovo_.nero_.png\",\"width\":150,\"height\":32,\"caption\":\"Arletti & Partners\"},\"image\":{\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArlettiPartners\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arletti-partners\"],\"description\":\"Tax & Global Mobility Law Firm in Italy\",\"email\":\"info@arlettipartners.com\",\"telephone\":\"+390230456361\",\"legalName\":\"Arletti Partners\",\"foundingDate\":\"1998-01-01\",\"vatID\":\"IT02519610360\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/#\\\/schema\\\/person\\\/a592359405c2816205501785c0543c7c\",\"name\":\"Salvatore La Rocca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g\",\"caption\":\"Salvatore La Rocca\"},\"knowsLanguage\":[\"Chinese\",\"English\",\"Italian\",\"Spanish\"],\"url\":\"https:\\\/\\\/arlettipartners.com\\\/de\\\/author\\\/salvatore-la-rocca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die finnische Steuernummer und die Valtti-Karte - Arletti Partners","description":"Erfahren Sie mehr \u00fcber die Beantragung der Valtti-Karte und der finnischen Steuernummer f\u00fcr Arbeitnehmer, die nach Finnland entsandt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/","og_locale":"de_DE","og_type":"article","og_title":"Die finnische Steuernummer und die Valtti-Karte","og_description":"In Finnland ist die Einhaltung der Vorschriften f\u00fcr Bau- und Werftarbeiten von entscheidender Bedeutung. In diesem Zusammenhang spielen die finnische Steuernummer und die Valtti-Karte eine zentrale Rolle.","og_url":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/","og_site_name":"Arletti Partners","article_publisher":"https:\/\/www.facebook.com\/ArlettiPartners","article_published_time":"2025-01-21T08:47:11+00:00","article_modified_time":"2025-01-24T07:55:05+00:00","og_image":[{"width":1300,"height":700,"url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png","type":"image\/png"}],"author":"Salvatore La Rocca","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Salvatore La Rocca","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#article","isPartOf":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/"},"author":{"name":"Salvatore La Rocca","@id":"https:\/\/arlettipartners.com\/de\/#\/schema\/person\/a592359405c2816205501785c0543c7c"},"headline":"Die finnische Steuernummer und die Valtti-Karte","datePublished":"2025-01-21T08:47:11+00:00","dateModified":"2025-01-24T07:55:05+00:00","mainEntityOfPage":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/"},"wordCount":878,"publisher":{"@id":"https:\/\/arlettipartners.com\/de\/#organization"},"image":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png","articleSection":["Administrative Fulfilments","Administrative Fulfilments"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/","url":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/","name":"Die finnische Steuernummer und die Valtti-Karte - Arletti Partners","isPartOf":{"@id":"https:\/\/arlettipartners.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#primaryimage"},"image":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#primaryimage"},"thumbnailUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png","datePublished":"2025-01-21T08:47:11+00:00","dateModified":"2025-01-24T07:55:05+00:00","description":"Erfahren Sie mehr \u00fcber die Beantragung der Valtti-Karte und der finnischen Steuernummer f\u00fcr Arbeitnehmer, die nach Finnland entsandt werden.","breadcrumb":{"@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#primaryimage","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2025\/01\/Progetto-senza-titolo-4-1.png","width":1300,"height":700,"caption":"valtti card and finnish tax number"},{"@type":"BreadcrumbList","@id":"https:\/\/arlettipartners.com\/de\/die-finnische-steuernummer-und-die-valtti-karte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arlettipartners.com\/de\/"},{"@type":"ListItem","position":2,"name":"Health &amp; Safety at Work for Employees","item":"https:\/\/arlettipartners.com\/de\/category\/health-safety-at-work-for-employees\/"},{"@type":"ListItem","position":3,"name":"Administrative Fulfilments","item":"https:\/\/arlettipartners.com\/de\/category\/health-safety-at-work-for-employees\/administrative-fulfilments\/"},{"@type":"ListItem","position":4,"name":"Die finnische Steuernummer und die Valtti-Karte"}]},{"@type":"WebSite","@id":"https:\/\/arlettipartners.com\/de\/#website","url":"https:\/\/arlettipartners.com\/de\/","name":"Arletti Partners","description":"Tax Advisors and Global Mobility Specialists","publisher":{"@id":"https:\/\/arlettipartners.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arlettipartners.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arlettipartners.com\/de\/#organization","name":"Arletti & Partners","alternateName":"Studio Arletti","url":"https:\/\/arlettipartners.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arlettipartners.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","contentUrl":"https:\/\/arlettipartners.com\/wp-content\/uploads\/2022\/03\/cropped-logo.png.nuovo_.nero_.png","width":150,"height":32,"caption":"Arletti & Partners"},"image":{"@id":"https:\/\/arlettipartners.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ArlettiPartners","https:\/\/www.linkedin.com\/company\/arletti-partners"],"description":"Tax & Global Mobility Law Firm in Italy","email":"info@arlettipartners.com","telephone":"+390230456361","legalName":"Arletti Partners","foundingDate":"1998-01-01","vatID":"IT02519610360","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/arlettipartners.com\/de\/#\/schema\/person\/a592359405c2816205501785c0543c7c","name":"Salvatore La Rocca","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39abdc5dcc5c3b71d74c08ca1efcd426151ae65221da985e1c71297f1465b486?s=96&d=mm&r=g","caption":"Salvatore La Rocca"},"knowsLanguage":["Chinese","English","Italian","Spanish"],"url":"https:\/\/arlettipartners.com\/de\/author\/salvatore-la-rocca\/"}]}},"_links":{"self":[{"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/posts\/186204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/comments?post=186204"}],"version-history":[{"count":0,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/posts\/186204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/media\/186007"}],"wp:attachment":[{"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/media?parent=186204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/categories?post=186204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/tags?post=186204"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/country?post=186204"},{"taxonomy":"container","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/container?post=186204"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/service?post=186204"},{"taxonomy":"tag-di-competenza","embeddable":true,"href":"https:\/\/arlettipartners.com\/de\/wp-json\/wp\/v2\/tag-di-competenza?post=186204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}